{"id":15296,"date":"2024-04-23T22:09:58","date_gmt":"2024-04-23T20:09:58","guid":{"rendered":"https:\/\/www.nexova.ch\/?p=15296"},"modified":"2025-10-09T21:21:00","modified_gmt":"2025-10-09T19:21:00","slug":"automatisierung-der-kreditorenbuchhaltung-mit-continia","status":"publish","type":"post","link":"https:\/\/www.nexova.ch\/de\/buchhaltung\/automatisierung-der-kreditorenbuchhaltung-mit-continia\/","title":{"rendered":"Automatisierung der Kreditorenbuchhaltung mit Continia"},"content":{"rendered":"\n<section class=\"wp-block-qweb-blog-section blog-section\"><div class=\"blog-section-wrap\"><h1 class=\"blog-section-title\">Automatisierung der Kreditorenbuchhaltung mit Continia<\/h1>\n<figure class=\"wp-block-image size-full resp\"><picture><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/11\/shutterstock_1828586459_2-edited.jpg\" media=\"(min-width: 981px)\"\/><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/11\/shutterstock_1828586459_2-edited-1-768x461.jpg\" media=\"(max-width: 980px)\"\/><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" class=\"lazyload wp-image-19226\"\/><\/picture><\/figure>\n\n\n\n<p>Finanzoperationen sind der Motor, der die Entwicklung eines Unternehmens antreibt. Doch in der heutigen Gesch\u00e4ftswelt ist die Transformation greifbar: Finanzielle Klarheit, Genauigkeit in Transaktionen und optimierte Arbeitsabl\u00e4ufe sind nicht nur erreichbar, sondern auch zug\u00e4nglicher denn je dank moderner Business- und Buchhaltungssoftware.<\/p>\n\n\n\n<p>Inmitten dieser Vielfalt an L\u00f6sungen steht die Kreditorensoftware im Rampenlicht. Auf unserer gemeinsamen Reise in diesem Blog werden wir ein Profil eines herausragenden Anw\u00e4rters auf dem heutigen Markt erstellen &#8211; besonders f\u00fcr Schweizer Unternehmer und KMU. Bereit, die Zukunft des Finanzmanagements zu erkunden?<\/p>\n<div class=\"cta-block\"><p class=\"blog-section-content\">Buchen Sie ein kostenloses Erstgespr\u00e4ch mit unseren Experten.<\/p><a class=\"cta-button\" href=\"https:\/\/www.nexova.ch\/de\/termin-buchen\/\">Termin buchen<\/a><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-qweb-blog-highlights blog-section highlights\"><div class=\"blog-section-wrap\"><div class=\"blog-highlights\"><h2 class=\"section-title\">Highlights<\/h2><ul class=\"higlight-lists\"><li class=\"higlight-list\"><span class=\"higlight-icon\"><\/span><span class=\"higlight-content\"><strong>Continia<\/strong> verbessert <strong>Effizienz<\/strong> in Finanzabteilungen<\/span><\/li><li class=\"higlight-list\"><span class=\"higlight-icon\"><\/span><span class=\"higlight-content\">Automatisierte <strong>Rechnungsbearbeitung<\/strong> reduziert <strong>Fehler<\/strong><\/span><\/li><li class=\"higlight-list\"><span class=\"higlight-icon\"><\/span><span class=\"higlight-content\"><strong>Spesenmanagement<\/strong> erleichtert <strong>Ausgabenkontrolle<\/strong><\/span><\/li><li class=\"higlight-list\"><span class=\"higlight-icon\"><\/span><span class=\"higlight-content\"><strong>Zahlungsmanagement<\/strong> optimiert <strong>Lieferantenbeziehungen<\/strong><\/span><\/li><li class=\"higlight-list\"><span class=\"higlight-icon\"><\/span><span class=\"higlight-content\"><strong>Sicherheitsfunktionen<\/strong> sch\u00fctzen vor <strong>Betrug<\/strong><\/span><\/li><\/ul><\/div><div class=\"blog-content-list\"><h2 class=\"section-title\">Inhalt<\/h2><ul class=\"content-lists\"><li class=\"content-list\">Automatisierung der Kreditorenbuchhaltung mit Continia<\/li><li class=\"content-list\">Highlights &#038; Inhalt<\/li><li class=\"content-list\">Warum in eine robuste Kreditoren Software investieren?<\/li><li class=\"content-list\">Was ist Continia?&nbsp;<\/li><li class=\"content-list\">Die wichtigsten Funktionen von Finanzabteilungen<\/li><li class=\"content-list\">Entdecken Sie Continia: Schl\u00fcsselkomponenten zur Neugestaltung des Finanzmanagements<\/li><li class=\"content-list\">Partnerschaft mit Nexova f\u00fcr fachkundige Beratung und Unterst\u00fctzung<\/li><li class=\"content-list\">Das sagen unsere Kunden<\/li><\/ul><div class=\"more-button\"><span class=\"qicon q-arrow-down\"><\/span><\/div><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-qweb-blog-section blog-section\"><div class=\"blog-section-wrap\"><h2 class=\"blog-section-title\">Warum in eine robuste Kreditoren Software investieren?<\/h2>\n<figure class=\"wp-block-image size-full top resp\"><picture><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2025\/08\/shutterstock_2208577873-edited.jpg\" media=\"(min-width: 981px)\"\/><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/03\/shutterstock_2208577873.jpg\" media=\"(max-width: 980px)\"\/><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" class=\"lazyload wp-image-28756\"\/><\/picture><\/figure>\n\n\n\n<p>Finanzoperationen bestimmen die Entwicklung eines Unternehmens vielleicht mehr als jede andere T\u00e4tigkeit.&nbsp; Wie ein altes Sprichwort sagt: &#8222;Cash is King&#8220;, und die finanzielle Gesundheit Ihres Unternehmens sollte immer im Vordergrund stehen.&nbsp;<\/p>\n\n\n\n<p>Finanzteams stellen sicher, dass jede Transaktion in der <a href=\"https:\/\/www.nexova.ch\/de\/buchhaltung\/doppelte-buchhaltung\/\" data-type=\"post\" data-id=\"5699\">Finanzbuchhaltung<\/a> verbucht und jede Ressource sinnvoll verwaltet wird. Sie analysieren Daten und liefern strategische Erkenntnisse, die eine klare Entscheidungsfindung erm\u00f6glichen. Sie sorgen f\u00fcr die Stabilit\u00e4t des Budgets, die Einhaltung von Vorschriften und die effiziente Zuweisung von Verm\u00f6genswerten und sind damit die Abteilung, in der alle F\u00e4den zusammenlaufen.<\/p>\n\n\n\n<p>In der Vergangenheit wurden alle diese Vorg\u00e4nge mit Hilfe von Tabellenkalkulationen und Stift und Papier verwaltet.&nbsp; Wie man sich vorstellen kann, waren diese manuellen Methoden zeitaufw\u00e4ndig, fehleranf\u00e4llig und erleichterten die Kommunikation zwischen den Abteilungen und mit den F\u00fchrungskr\u00e4ften nicht gerade.&nbsp;<\/p>\n\n\n\n<p>Im Laufe der Jahre begannen Finanzteams, Systemanalytiker und Programmierer gleichermassen, sich auf die Rationalisierung der verschiedenen Finanzprozesse zu konzentrieren, die Zuverl\u00e4ssigkeit und Genauigkeit zu erh\u00f6hen und zu kl\u00e4ren, wohin die Ressourcen eines Unternehmens fliessen.&nbsp; Der H\u00f6hepunkt dieser Bem\u00fchungen, die hochmoderne Finanzautomatisierungsl\u00f6sung und Business Software, steht hier im Mittelpunkt: Continia.<\/p>\n<div class=\"cta-block\"><p class=\"blog-section-content\">Buchen Sie ein kostenloses Erstgespr\u00e4ch mit unseren Experten.<\/p><a class=\"cta-button\" href=\"https:\/\/www.nexova.ch\/de\/termin-buchen\/\">Termin buchen<\/a><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-qweb-blog-section blog-section\"><div class=\"blog-section-wrap\"><h2 class=\"blog-section-title\">Was ist Continia?&nbsp;<\/h2>\n<figure class=\"wp-block-image size-full resp\"><picture><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2025\/08\/shutterstock_1702395682_2-edited.jpg\" media=\"(min-width: 981px)\"\/><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/03\/shutterstock_1702395682_2.jpg\" media=\"(max-width: 980px)\"\/><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" class=\"lazyload wp-image-28758\"\/><\/picture><\/figure>\n\n\n\n<p>Lassen Sie uns zun\u00e4chst einen allgemeinen \u00dcberblick \u00fcber die Software geben, bevor wir die verschiedenen Funktionen der Plattform aufschl\u00fcsseln und erl\u00e4utern, wie sie Ihrem Unternehmen dienen k\u00f6nnen.<\/p>\n\n\n\n<p>Continia ist eine Finanzsoftware, die Aufgaben wie die Rechnungsbearbeitung, die Erstattung von Mitarbeiterausgaben und die Dokumentenverwaltung automatisiert und vereinfacht und so die Effizienz und Genauigkeit in Finanzabteilungen erheblich verbessert.&nbsp;<\/p>\n\n\n\n<p>Die Produkte von Continia, die wir einzeln aufschl\u00fcsseln werden, wie Continia Document Capture und Continia Expense Management, k\u00f6nnen verschiedene Aspekte der Kreditorenbuchhaltung automatisieren.&nbsp;<\/p>\n\n\n\n<p>Durch die Automatisierung von Schl\u00fcsselaufgaben wie Rechnungsverarbeitung, Genehmigungsworkflows und Zahlungsmanagement rationalisiert Continia den Kreditorenbuchhaltungsprozess von Anfang bis Ende, spart Zeit, reduziert Fehler und verbessert die Gesamteffizienz.&nbsp; (Sollten Ihnen die Kreditorenbuchhaltung, auch bekannt als Kreditorenkonten, nicht vertraut sein, werden wir Ihnen gerne einen \u00dcberblick \u00fcber die grundlegenden Finanzoperationen geben.)<\/p>\n\n\n\n<p>Durch die Integration mit der <a href=\"https:\/\/www.nexova.ch\/de\/buchhaltung\/auslagerung-der-buchhaltung-mit-microsoft-dynamics-365-business-central\/\" data-type=\"post\" data-id=\"10761\">ERP Software Microsoft Dynamics 365 Business Central<\/a> gew\u00e4hrleistet Continia einen nahtlosen Datenfluss und verbessert die allgemeinen Finanzmanagement-Funktionen f\u00fcr Unternehmen.&nbsp; Sp\u00e4ter im Blog werden wir darauf eingehen, warum ein Unternehmen von On-Premises- auf Cloud-basierte Software umsteigt, aber f\u00fcr den Moment gen\u00fcgt es zu sagen, dass Cloud-basierte Systeme nicht zuf\u00e4llig zur Norm geworden sind.&nbsp; Zentralisierte Daten, verbesserte Zusammenarbeit und Echtzeitdaten machen diese Einrichtung f\u00fcr viele Nutzer \u00e4u\u00dferst vorteilhaft.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Bevor wir uns an die spezifischen Funktionen der Software-Plattform von Continia wagen, sollten wir uns die grundlegenden Funktionen der Finanzabteilungen in Unternehmen vergegenw\u00e4rtigen.&nbsp; Danach k\u00f6nnen wir uns ein Bild davon machen, wie die Funktionen von Continia Ihr Unternehmen voranbringen k\u00f6nnen.<\/p>\n<div class=\"cta-block\"><p class=\"blog-section-content\">Buchen Sie ein kostenloses Erstgespr\u00e4ch mit unseren Experten.<\/p><a class=\"cta-button\" href=\"https:\/\/www.nexova.ch\/de\/termin-buchen\/\">Termin buchen<\/a><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-qweb-blog-section blog-section\"><div class=\"blog-section-wrap\"><h2 class=\"blog-section-title\">Die wichtigsten Funktionen von Finanzabteilungen<\/h2>\n<figure class=\"wp-block-image size-full resp\"><picture><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2025\/08\/shutterstock_1738087943_2-edited.jpg\" media=\"(min-width: 981px)\"\/><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/03\/shutterstock_1738087943_2.jpg\" media=\"(max-width: 980px)\"\/><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" class=\"lazyload wp-image-28760\"\/><\/picture><\/figure>\n\n\n\n<p>In diesem Abschnitt werden wir uns mit den Grundlagen der Finanzabteilungen im Hinblick auf ihre spezifischen Funktionen befassen, aber zuvor sollte gesagt werden, dass eine gut eingestellte Finanzabteilung unglaubliche Kaskadeneffekte haben kann.&nbsp; Wie bereits erw\u00e4hnt, ist Geld das Lebenselixier eines jeden Unternehmens.&nbsp;<\/p>\n\n\n\n<p>Ein hohes Mass an Klarheit im Finanzbereich eines Unternehmens kann die Grundlage f\u00fcr eine klare Entscheidungsfindung im gesamten Unternehmen bilden, und die Genauigkeit und Zuverl\u00e4ssigkeit der Finanzdaten kann dazu beitragen, gute Ergebnisse zu wiederholen oder Lecks im Tagesgesch\u00e4ft zu schliessen.&nbsp; Werfen wir also einen kurzen Blick auf die spezifischen Funktionen, die in Finanzabteilungen ausge\u00fcbt werden.<\/p>\n\n\n\n<p>Finanzabteilungen in Unternehmen erf\u00fcllen eine Vielzahl wichtiger Funktionen, um finanzielle Ressourcen effektiv zu verwalten und finanzielle Stabilit\u00e4t zu gew\u00e4hrleisten. Zu den grundlegenden Aufgaben einer Finanzabteilung geh\u00f6ren:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Finanzplanung und -analyse: <\/strong>Hier entwickeln und \u00fcberwachen wir die <a href=\"https:\/\/www.nexova.ch\/de\/business\/finanzplan-fuer-start-ups\/\" data-type=\"post\" data-id=\"15325\">Finanzpl\u00e4ne<\/a> und Budgets des Unternehmens, f\u00fchren Finanzanalysen durch, um die Leistung zu bewerten und Verbesserungsm\u00f6glichkeiten zu ermitteln.<\/li>\n\n\n\n<li><strong>Buchhaltung und Finanzberichterstattung: <\/strong>Mit einer sorgf\u00e4ltigen Buchf\u00fchrung k\u00f6nnen wir pr\u00e4zise Buchhaltungsunterlagen f\u00fchren, Finanztransaktionen aufzeichnen und Finanzberichte wie die Bilanz, die Erfolgsrechnung und die Geldflussrechnung in \u00dcbereinstimmung mit den Rechnungslegungsstandards und -vorschriften erstellen.&nbsp;&nbsp; &nbsp;<\/li>\n\n\n\n<li><strong>Kreditorenbuchhaltung:<\/strong> Hier verwalten wir die Zahlungen des Unternehmens an Verk\u00e4ufer und Lieferanten, indem wir Rechnungen bearbeiten, Genehmigungen f\u00fcr Zahlungen einholen und die rechtzeitige und korrekte Zahlung unter Einhaltung der Vertragsbedingungen sicherstellen.&nbsp; Kreditoren werden im Allgemeinen auch als Verbindlichkeiten aus Lieferungen und Leistungen bezeichnet.<\/li>\n\n\n\n<li><strong>Debitoren:<\/strong> Die Debitorenbuchhaltung ist das Gegenteil der Kreditorenbuchhaltung &#8211; sie verwaltet das Geld, das dem Unternehmen von Kunden f\u00fcr gelieferte, aber noch nicht bezahlte Waren oder Dienstleistungen geschuldet wird, und stellt sicher, dass die Forderungen rechtzeitig eingezogen werden.&nbsp;Debitoren werden auch als Forderungen aus Lieferungen und Leistungen bezeichnet. In der Debitorenbuchhaltung werden alle Rechnungen an Kunden erstellt und \u00fcberwacht.&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/li>\n\n\n\n<li><strong>Liquidit\u00e4tsmanagement:<\/strong> Die Liquidit\u00e4tsplanung hat die wichtige Aufgabe, den Cashflow des Unternehmens zu \u00fcberwachen und zu steuern, um eine ausreichende Liquidit\u00e4t zur Erf\u00fcllung der finanziellen Verpflichtungen und zur Finanzierung der betrieblichen Aktivit\u00e4ten zu gew\u00e4hrleisten, einschliesslich der Vorhersage des Bargeldbedarfs und der Optimierung der Bargeldbest\u00e4nde.&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/li>\n\n\n\n<li><strong>Finanzielles Risikomanagement:<\/strong> Das Risikomanagement ist eine eigenst\u00e4ndige Disziplin, die sich mit der Identifizierung, Bewertung und Abschw\u00e4chung finanzieller Risiken befasst, die sich auf die Leistung oder die finanzielle Stabilit\u00e4t des Unternehmens auswirken k\u00f6nnten, z. B. W\u00e4hrungsschwankungen, Zins\u00e4nderungen und Marktvolatilit\u00e4t.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<\/li>\n\n\n\n<li><strong>Budgetierung und Ausgabenmanagement:&nbsp;<\/strong>Hier geht es um die Entwicklung und \u00dcberwachung des Unternehmensbudgets, die Zuteilung von Ressourcen an verschiedene Abteilungen und Projekte und die Kontrolle der Ausgaben, um sicherzustellen, dass sie innerhalb der budgetierten Grenzen bleiben.<\/li>\n\n\n\n<li><strong>Einhaltung der Finanzvorschriften:<\/strong> Schliesslich sorgt die Finanzabteilung f\u00fcr die Einhaltung von Finanzvorschriften, Rechnungslegungsstandards und internen Richtlinien und Verfahren. Dazu geh\u00f6ren die Erstellung von Finanzberichten f\u00fcr Aufsichtsbeh\u00f6rden, die Durchf\u00fchrung interner Pr\u00fcfungen und die Sicherstellung, dass Finanztransaktionen genau und transparent aufgezeichnet werden.<\/li>\n<\/ol>\n\n\n\n<p>Mit einem soliden Verst\u00e4ndnis der grundlegenden Aufgaben innerhalb der Finanzabteilungen sind wir nun bereit, uns n\u00e4her damit zu befassen, wie die spezifischen Funktionen einer Kreditorensoftware wie Continia diese Funktionen revolutionieren, Ihre Finanzoperationen rationalisieren und das Wachstum Ihres Unternehmens f\u00f6rdern k\u00f6nnen.<\/p>\n<div class=\"cta-block\"><p class=\"blog-section-content\">Berechnen Sie hier ganz einfach die Kosten Ihrer Buchhaltung.<\/p><a class=\"cta-button\" href=\"https:\/\/www.nexova.ch\/de\/buchhaltung\/\">Preisrechner<\/a><\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-qweb-blog-section blog-section\"><div class=\"blog-section-wrap\"><h2 class=\"blog-section-title\">Entdecken Sie Continia: Schl\u00fcsselkomponenten zur Neugestaltung des Finanzmanagements<\/h2>\n<figure class=\"wp-block-image size-full top resp\"><picture><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/03\/shutterstock_1075042007_2.jpg\" media=\"(min-width: 981px)\"\/><source srcset=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/03\/shutterstock_1075042007_2.jpg\" media=\"(max-width: 980px)\"\/><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" alt=\"\" class=\"lazyload wp-image-15252\"\/><\/picture><\/figure>\n\n\n\n<p>Wenn wir uns mit den M\u00f6glichkeiten von Continia besch\u00e4ftigen, wird deutlich, dass die robusten Funktionen von Continia im Zeitalter der Automatisierung nahezu unverzichtbar sind. Continia bietet eine Reihe von L\u00f6sungen zur Systematisierung von Routineaufgaben, zur Minimierung von Fehlern und zur Freisetzung von wertvoller Zeit f\u00fcr strategische Entscheidungen. Werfen wir einen Blick auf einige der wichtigsten Funktionen, die Continia zu einer herausragenden Wahl f\u00fcr das Finanzmanagement machen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Dokumentenerfassung:<\/h3>\n\n\n\n<p>Eine der wichtigsten Funktionen von Continia, die Dokumentenerfassung, revolutioniert die Art und Weise, wie Unternehmen Rechnungen und andere Finanzdokumente bearbeiten.&nbsp;<\/p>\n\n\n\n<p>Im Wesentlichen ist diese Funktion darauf ausgelegt, den Arbeitsablauf in der Kreditorenbuchhaltung zu automatisieren und zu rationalisieren.&nbsp;Dieses Tool nutzt die fortschrittliche OCR-Technologie (Optical Character Recognition), um Dokumente automatisch zu scannen, zu interpretieren und digital in den richtigen Feldern in Microsoft Dynamics 365 Business Central zu speichern.<\/p>\n\n\n\n<p>Durch das automatische Interpretieren und Extrahieren von Daten kann diese OCR-Technologie m\u00fchsame Dateneingaben \u00fcberfl\u00fcssig machen, menschliche Fehler reduzieren und die Effizienz und P\u00fcnktlichkeit der ausgehenden Zahlungen erh\u00f6hen. Sie integriert diese Dokumente nahtlos in Ihre Finanzabl\u00e4ufe und stellt sicher, dass sie leicht zug\u00e4nglich und sicher gespeichert sind.<\/p>\n\n\n\n<p>Diese Automatisierung reduziert den Zeitaufwand f\u00fcr die manuelle Dateneingabe und erh\u00f6ht die Genauigkeit Ihrer Finanzunterlagen.&nbsp; Einer der versteckten Vorteile der Minimierung der menschlichen Interaktion und des Zugriffs auf sensible Daten ist die erh\u00f6hte Sicherheit und die Vermeidung von Dokumentenbetrug.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Spesenmanagement:<\/h3>\n\n\n\n<p>Wenn Ihr Unternehmen w\u00e4chst und die Zahl der Mitarbeiter zunimmt, kann die Verwaltung der Mitarbeiterausgaben m\u00fchsam und fehleranf\u00e4llig werden. Continia Expense Management ist eine Funktion, die dies vereinfacht, indem es eine optimierte Plattform bereitstellt, auf der Mitarbeiter Ausgaben schnell einreichen und Manager sie mit nur wenigen Tastendr\u00fccken genehmigen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p>In Echtzeit gleicht das System automatisch Quittungen mit Spesenabrechnungen ab und sorgt so f\u00fcr Compliance und Transparenz. Diese Funktion beschleunigt nicht nur die Erstattungsprozesse, sondern bietet auch einen klaren Einblick in die Ausgabenmuster des Unternehmens und hilft so, die Budgets besser zu verwalten.&nbsp;<\/p>\n\n\n\n<p>Wenn diese Zahlen organisiert und leicht zug\u00e4nglich sind, k\u00f6nnen sie fast jede Abteilung des Finanzteams unterst\u00fctzen und eine klare Entscheidungsfindung bei der Festlegung von Unternehmenspriorit\u00e4ten erleichtern.&nbsp;&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Automatisiertes Zahlungsmanagement:<\/h3>\n\n\n\n<p>Wie wir allm\u00e4hlich feststellen k\u00f6nnen, zeichnet sich Continia durch die Automatisierung des Kreditorenprozesses aus. Vom Rechnungseingang bis zur Zahlungsausf\u00fchrung ist ihr System ein reibungsloser Fluss, der optimiert ist, um rechtzeitige und genaue Zahlungen zu gew\u00e4hrleisten. Automatisierte Workflows leiten die Rechnungen auf der Grundlage vordefinierter Regeln zur Genehmigung weiter, wodurch die Durchlaufzeit und menschliche Fehler erheblich reduziert werden.&nbsp;<\/p>\n\n\n\n<p>Mit diesem Zahlungsmanagementsystem erhalten wir einen klaren \u00dcberblick \u00fcber alle Lieferanten-, Mitarbeiter- und Kundenzahlungen sowie Gutschriften direkt aus Microsoft Dynamics 365 Business Central. Continia bietet robuste Optionen f\u00fcr die Zahlungsabwicklung, unterst\u00fctzt verschiedene Zahlungsmethoden und integriert sich mit mehreren Banken und deren e banking L\u00f6sungen, was reibungslosere Finanztransaktionen weltweit erm\u00f6glicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. Eine einheitliche Sicht auf die Finanzoperationen:<\/h3>\n\n\n\n<p>Ein entscheidender Vorteil von Continia ist die Integration mit ERP Systemen wie Microsoft Dynamics 365 Business Central. Diese Verbindung stellt sicher, dass die Daten nahtlos zwischen den Systemen fliessen und die Genauigkeit und Konsistenz der Finanzdaten in Echtzeit erhalten bleibt.<\/p>\n\n\n\n<p>Sie verbessert die Gesamtkapazit\u00e4ten des Finanzmanagements, indem sie eine einheitliche Sicht auf die Finanzoperationen bietet, die f\u00fcr die strategische Planung und Analyse entscheidend ist. In der heutigen schnelllebigen Gesch\u00e4ftswelt ist der Zugang zu Echtzeit-Finanzdaten unerl\u00e4sslich. Continia bietet leistungsstarke Reporting-Tools, die auf einen Blick Einblicke in die finanzielle Performance erm\u00f6glichen.<\/p>\n\n\n\n<p>Anpassbare Dashboards erm\u00f6glichen es den Finanzteams, die wichtigsten Kennzahlen und Trends zu \u00fcberwachen, was ein proaktives Management der finanziellen Gesundheit und eine schnelle Anpassung an sich \u00e4ndernde Marktbedingungen erm\u00f6glicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Erweiterte Sicherheit und Betrugsbek\u00e4mpfung:&nbsp;<\/h3>\n\n\n\n<p>Leider leben wir in einer Zeit, in der immer raffiniertere Betrugsmaschen ausgeheckt werden.&nbsp; Neben den allt\u00e4glichen Vorteilen der Continia-Software kann sie eine wichtige Rolle bei der Betrugspr\u00e4vention in Finanzabteilungen spielen, indem sie betr\u00fcgerische Aktivit\u00e4ten aufdeckt, verhindert und eind\u00e4mmt.<\/p>\n\n\n\n<p>Durch die elektronische Erfassung und Speicherung aller Finanztransaktionen wird ein umfassender Pr\u00fcfpfad erstellt, mit dem Transaktionen nachverfolgt und \u00fcberpr\u00fcft werden k\u00f6nnen, wodurch das Risiko betr\u00fcgerischer Aktivit\u00e4ten wie Rechnungsmanipulation oder -duplizierung verringert wird. Durch die Automatisierung von Spesenberichten, Genehmigungsabl\u00e4ufen und R\u00fcckerstattungsprozessen wird das Risiko von betr\u00fcgerischen Spesenabrechnungen oder nicht genehmigten Ausgaben verringert.<\/p>\n\n\n\n<p>Durch die Zentralisierung von Zahlungsworkflows, die Implementierung von mehrstufigen Genehmigungsprozessen und die Integration mit sicheren Zahlungsgateways werden nicht autorisierte Zahlungen und betr\u00fcgerische Aktivit\u00e4ten wie Zahlungsbetrug oder nicht autorisierte Geld\u00fcberweisungen verhindert.<\/p>\n<div class=\"cta-block\"><p class=\"blog-section-content\">Buchen Sie ein kostenloses Erstgespr\u00e4ch mit unseren Experten.<\/p><a class=\"cta-button\" href=\"https:\/\/www.nexova.ch\/de\/termin-buchen\/\">Termin buchen<\/a><\/div><\/div><\/section>\n\n\n    <section class=\"wp-block-qweb-blog-conclusion blog-section conclusion\">\n        <div class=\"blog-section-wrap\">\n                            <h2 class=\"blog-section-title\">Partnerschaft mit Nexova f\u00fcr fachkundige Beratung und Unterst\u00fctzung<\/h2>\n            \n                            <figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1080\" height=\"602\" src=\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2026\/02\/Team_Patch_Y2.jpg-1900x1059.jpg\" class=\"nexova-team-img nexova-yellow\" alt=\"Team_Patch_Y2.jpg\" loading=\"lazy\" \/><\/figure>\n            \n            <div class=\"blog-section-content\">\n\n<p>Nachdem wir nun einen Einblick in die robusten Funktionen und Vorteile von Continia gewonnen haben, verstehen Sie sicherlich die immense Bedeutung einer effizienten und zuverl\u00e4ssigen Finanzmanagementl\u00f6sung f\u00fcr Ihr Unternehmen. Doch die Implementierung einer solchen L\u00f6sung ist oft komplex und erfordert fundiertes Fachwissen sowie strategische Planung.<\/p>\n\n\n\n<p>Warum sollten Sie diesen herausfordernden Prozess allein bew\u00e4ltigen, wenn Ihnen unsere Experten von Nexova zur Seite stehen k\u00f6nnen? Neben unserem umfassenden Angebot an Finanzbuchhaltung- und <a href=\"https:\/\/www.nexova.ch\/de\/\" target=\"_blank\" data-type=\"page\" data-id=\"6676\" rel=\"noreferrer noopener\">Treuhanddienstleistungen f\u00fcr KMUs und Start-ups in der Schweiz<\/a> bietet Nexova professionelle Beratungsdienstleistungen an.<\/p>\n\n\n\n<p>Unsere Experten k\u00f6nnen Ihnen helfen, Ihre individuellen Anforderungen zu analysieren und fundierte Entscheidungen zu treffen, sei es bei der Implementierung von Continia oder bei der Optimierung Ihrer gesamten Finanzprozesse.<\/p>\n\n\n\n<p>Z\u00f6gern Sie nicht l\u00e4nger und nehmen Sie noch heute Kontakt mit uns auf, um herauszufinden, wie wir Ihnen helfen k\u00f6nnen, Ihr Unternehmen auf dem Weg zu nachhaltigem Erfolg zu unterst\u00fctzen.<\/p>\n\n<\/div>\n        <\/div>\n    <\/section>\n    \n\n<section class=\"wp-block-qweb-customer-review blog-section customer-review\">\n\t<div class=\"blog-section-wrap\">\n\t\t<div class=\"section-row\">\n\t\t\t<div class=\"section-col title-col\">\n\t\t\t\t<h2 class=\"section-title\">Das sagen unsere Kunden<\/h2>\n\t\t\t\t<p class=\"tx-large-size\">Ihre Meinung z\u00e4hlt<\/p>\n\t\t\t<\/div>\n\t\t\t<div>\n\t\t\t\t<div class=\"google-rating\">\n\t\t\t\t  <div class=\"map-ico\">\n\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/04\/google-map.svg\" width=\"42\" height=\"60\" alt=\"Google map icon for nexova rating\">\n\t\t\t\t  <\/div>\n\t\t\t\t  <div class=\"rating\">\n\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/2022\/04\/five-star.svg\" width=\"180\" height=\"28\" alt=\"nexova rating is 5 star\">\n\t\t\t\t\t<h3>5.0 Sterne <\/h3>\n\t\t\t\t\t<div>\n\t\t\t\t\t  93 Bewertungen \n\t\t\t\t\t<\/div>\n\t\t\t\t  <\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\t\t\n\t\t<div class=\"q_reviews\">\n\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/01\/unnamed-4.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tMarc Perren\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p class=\"p1\">Herr Merz verf\u00fcgt \u00fcber ein sehr breites Wissen und konnte mir bei allen Fragen weiterhelfen. Das Gespr\u00e4ch verlief sehr angenehm und war f\u00fcr mich sehr aufschlussreich. Vielen Dank f\u00fcr Ihre Unterst\u00fctzung.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/01\/unnamed-3.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tJ\u00f6rg Buckmann\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p class=\"p1\">Unkompliziert oder seri\u00f6s? Oder heisst hier und. Hier ist ein junges, kluges Team am Werk, das ausgezeichnete Services anbietet, h\u00f6chst unkompliziert und kompetent. Statt einem repr\u00e4sentativen Empfang, teuren B\u00fcros und Sch\u00f6ggeli gibt es schnelle Services und kompetente Dienstleistungen. F\u00fcr mich als 1-Mann GmbH genau das, was ich brauche.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/01\/unnamed-2.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tMartin Gerber\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p class=\"p1\">Ich bin nun seit einiger Zeit Kunde bei Nexova und bin bis jetzt sehr zufrieden! Insbesondere im t\u00e4glichen Ablauf verliert man durch die digitale Arbeitsweise und hohe Responsivit\u00e4t der Mandatsleiter wenig Zeit. Zudem sind die Preise sehr fair. Nexova erledigt f\u00fcr mich die Jahresabschl\u00fcsse inklusive Steuerbilanz. Die Prozesse sind standardisiert was f\u00fcr Revisionen (AHV und Steuern) ein sehr grosser Vorteil ist. Die beiden Gr\u00fcnder sind zwei junge, innovative Typen und top seri\u00f6s.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/01\/unnamed-1.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tFlorian Kreidler\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p class=\"p1\">Der freundliche und kompetente Mitarbeiter von Nexova konnte mir schnell und zielgerichtet meine Fragen zur Firmenwagenbesteuerung beantworten. Herzlichen Dank hierf\u00fcr!<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2024\/01\/unnamed.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tReto S\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p class=\"p1\">Als ich vor einem Jahr meine Firma gegr\u00fcndet habe, brauchte ich einen zuverl\u00e4ssigen Treuhandpartner. Nexova bietet mir neben der reinen Buchhaltung auch eine sehr gute Beratung rund um arbeitsrechtliche Themen. Dank der E-Post L\u00f6sung muss ich mich nicht einmal mehr um meine Firmenpost k\u00fcmmern und kann mich rein auf meine Dienstleistungst\u00e4tigkeit fokussieren. Meine Ansprechpartner innerhalb Nexova sind stets sehr freundlich und angenehm im Umgang. Das Komplettpaket ist einfach nur TOP und ich kann Nexova nur weiterempfehlen!<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-8.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tPascal Zumstein\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Top Unternehmen &amp; freundliche Inhaber. Ein sehr empfehlenswerter Treuh\u00e4nder.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-7.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tSeb Ur\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Sehr gute und kompetente Beratung!<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-6.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tLouis Revel\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Sehr zufrieden mit der geleisteten Arbeit und dem angebotenen Service in Bezug auf Qualit\u00e4t und Preis. Ich empfehle sehr<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-5.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tDavid Leu\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Fachlich auf einem sehr hohen Niveau. Sie sind sehr gut mit Excel und konnten uns auch mit der Automatisierung von Prozessen unterst\u00fctzen.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-4.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tStefan Burgener\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Ich hatte ein paar Fragen zum Thema Remote Arbeit und wurde super und kostenlos beraten. Vielen Dank!<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-3.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tLuca M\u00e4rki\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Sehr guter Service. Gute und kompetente Beratung mit freundlichem Personal. Kann ich auf jeden Fall weiterempfehlen<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-2.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tEdward Buchanan\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Das Nexova-Team ist sehr professionell, und ich hatte das Gef\u00fchl, dass sie immer mein Bestes im Sinn hatten. Ich kann Nexova nur empfehlen und werde meine Kunden weiterhin an sie verweisen und ihnen mein Gesch\u00e4ft anvertrauen.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed-1.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tJuliam Pantano\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Ich bin beeindruckt von ihrem hervorragenden Service, vor allem im Bereich der Buchhaltungsdienstleistungen zeigen sie einen professionellen Ansatz und au\u00dfergew\u00f6hnliche Sorgfalt. Als Anwalt habe ich Nexova als wertvollen Partner in der Finanzwelt kennengelernt.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/10\/unnamed.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tMarie Ospina\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Ich hatte eine ausgezeichnete Beratung mit Nexova AG bez\u00fcglich der Quellensteuer. Ihr Fachwissen ist bemerkenswert umfangreich und ihre Beratung war von unsch\u00e4tzbarem Wert, ich kann ihre Dienste nur empfehlen. Eine erstklassige Erfahrung.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/04\/alan.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tAlan Sch\u00fctz\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Das Nexova-Team ist ein wichtiger Partner f\u00fcr unser Startup, mit dem wir alle unsere Buchhaltungs-, Steuer- und Lohnbuchhaltungsaufgaben erledigen k\u00f6nnen. Wir sch\u00e4tzen besonders ihre Erfahrung mit Startups und ihre Flexibilit\u00e4t, die es uns erm\u00f6glicht, unsere Finanzen effektiv zu planen und zu verwalten und uns auf das Endergebnis unserer Aktivit\u00e4ten zu konzentrieren.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/04\/raphel.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tRaphael H.\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Wir sind sehr zufrieden mit Nexova als unseren Treuh\u00e4nder. Dank der Teams-Chat-Gruppe kann ich mich immer auf sehr schnelle R\u00fccklaufzeiten (von wenigen Minuten) verlassen. Die Teams Chat Gruppe ist super. Bei unserem alten Treuh\u00e4nder mussten wir Mails schreiben und mussten immer lange auf eine Antwort warten und zudem wurde dann noch jede noch so kleine Frage in Rechnung gestellt. Dies ist bei Nexova gl\u00fccklicherweise nicht der Fall.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"reviews_col\">\n\t\t\t\t<div class=\"review_wrap\">\n\t\t\t\t\t<div class=\"review_head\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"avatar\" style=\"background-image:url('https:\/\/www.nexova.ch\/wp-content\/uploads\/2023\/04\/philip.png')\">\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"title\">\n\t\t\t\t\t\t\t<div class=\"reviewer\">\n\t\t\t\t\t\t\t\tPhilip Reck\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"google_logo\">\n\t\t\t\t\t\t\t<img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/google.png.webp' width='24'>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"star_rating\">\n\t\t\t\t\t\t<ul class=\"stars\">\n\t\t\t\t\t\t\t<li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li><li><img src='https:\/\/www.nexova.ch\/wp-content\/themes\/Qweb\/Images\/star.png.webp' width='22'><\/li>\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"review_content\">\n\t\t\t\t\t\t<p>Nexova hat mein Problem mit einem Mietnomaden schnell und effizient gel\u00f6st. Ich war mit der Situation schlicht \u00fcberfordert und froh \u00fcber die kompetente Rechtsberatung. Nexova hat von der Mahnung mit K\u00fcndigungsandrohung, \u00fcber die Vertretung vor Gericht bis hin zur polizeilichen R\u00e4umung alles schnell, effizient und auch preiswert erledigt. Vielen Dank f\u00fcr die wertvolle Hilfe.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"read_more\" style=\"opacity:0;pointer-events: none;\">\n\t\t\t\t\t\t<span href=\"#\" data-collapse='Mehr' data-open='Weniger'>Mehr<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<div class=\"review-button\">\n\t\t<a href=\"https:\/\/g.page\/r\/Cb30_RVpXzU_EBM\/review\" class=\"btn bold violet btn-with-bg\" target=\"_blank\" rel=\"nofollow\">Bewertung schreiben<\/a>\n\t<\/div>\n\t\t<style>\n\t\t\tsection.blog-section.customer-review {\n\t\t\tpadding-left: 10%;\n\t\t\tpadding-right: 10%;\n\t\t\tpadding-top: 4em;\n\t\t}\n\t\t\tsection.blog-section.customer-review .section-row{\n\t\t\t\tdisplay: flex;\n\t\t\t\tjustify-content: space-between;\n\t\t\t}\n\t\t\t.customer-review h2.section-title{\n\t\t\t\tmargin-bottom: 0 !important;\n\t\t\t}\n\t\t\tsection.blog-section.customer-review .google-rating .rating h3{\n\t\t\t\tpadding-bottom: 2px;\n\t\t\t\tfont-size: 19px !important;\n\t\t\t\tcolor: #666;\n\t\t\t}\n\t\t\t.q_reviews{\n\t\t\t\tposition: relative;\n\t\t\t\tpadding: 0 30px;\n\t\t\t\tmargin-top: 6em;\n\t\t\t}\n\t\t\t.q_reviews .slick-list{\n\t\t\t\toverflow: hidden;\n\t\t\t}\n\t\t\t.q_reviews .slick-track{\n\t\t\t\tdisplay: flex;\n\t\t\t\tgrid-gap: 20px;\n\t\t\t}\n\t\t\t.q_reviews .slick-arrow{\n\t\t\t\tposition: absolute;\n\t\t\t\ttop: calc(50% - 50px);\n\t\t\t\ttransform: translateY(-50%);\n\t\t\t\tfont-size: 0;\n\t\t\t\tborder: none;\n\t\t\t\tbackground: transparent;\n\t\t\t}\n\t\t\t.q_reviews .slick-arrow:after{\n\t\t\t\tfont-family: qicons!important;\n\t\t\t\tspeak: never;\n\t\t\t\tfont-style: normal;\n\t\t\t\tfont-weight: 400;\n\t\t\t\tfont-variant: normal;\n\t\t\t\ttext-transform: none;\n\t\t\t\tline-height: 1;\n\t\t\t\t-webkit-font-smoothing: antialiased;\n\t\t\t\tposition: absolute;\n\t\t\t\tleft: -1.3em;\n\t\t\t\ttop: 50%;\n\t\t\t\ttransform: translateY(-50%);\n\t\t\t\tfont-size: 26px;\n\t\t\t\tfont-weight: var(--bold);\n\t\t\t\tcursor: pointer;\n\t\t\t}\n\t\t\t.q_reviews .slick-prev{\n\t\t\t\tleft: 30px;\n\t\t\t}\n\t\t\t.q_reviews .slick-prev:after{\n\t\t\t\tcontent: \"\\e901\";\n\t\t\t}\n\t\t\t.q_reviews .slick-next:after{\n\t\t\t\tcontent: \"\\e902\";\n\t\t\t}\n\t\t\t.q_reviews .slick-next{\n\t\t\t\tright: -25px;\n\t\t\t}\n\t\t\t.q_reviews .slick-dots{\n\t\t\t\tpadding: 0;\n\t\t\t\tlist-style: none;\n\t\t\t\tdisplay: flex;\n\t\t\t\tjustify-content: center;\n\t\t\t\tmargin-top: 50px;\n\t\t\t}\n\t\t\t.q_reviews .slick-dots li{\n\t\t\t\tmargin-right: 10px;\n\t\t\t\tpadding-left: 0 !important;\n\t\t\t}\n\t\t\t.q_reviews .slick-dots li:before{\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t\t.q_reviews .slick-dots li:last-child{\n\t\t\t\tmargin-right: 0;\n\t\t\t}\n\t\t\t.q_reviews .slick-dots li button{\n\t\t\t\tborder: none;\n\t\t\t\twidth: 14px;\n\t\t\t\theight: 14px;\n\t\t\t\tborder-radius: 7px;\n\t\t\t\tfont-size: 0;\n\t\t\t\tbackground: #f7f5ff;\n\t\t\t\tcursor: pointer;\n\t\t\t\tpadding: 0;\n\t\t\t\tbox-sizing:border-box;\n\t\t\t}\n\t\t\tsection.blog-section:nth-child(odd) .q_reviews .slick-dots li button{\n\t\t\t\tbackground: #eceaf7;\n\t\t\t}\n\t\t\t.q_reviews .slick-dots li.slick-active button{\n\t\t\t\tbackground: var(--primary-color) !important;\n\t\t\t}\n\t\t\t.q_reviews .review_wrap{\n\t\t\t\tbackground: #f7f5ff;\n\t\t\t\tpadding: 25px;\n\t\t\t\tborder-radius: 8px;\n\t\t\t\tfont-size: 16px !important;\n\t\t\t\tfont-weight: var(--regular);\n\t\t\t\tdisplay: flex;\n\t\t\t\tflex-direction: column;\n\t\t\t}\n\t\t\tsection.blog-section:nth-child(odd) .q_reviews .review_wrap{\n\t\t\t\tbackground: #ffffff;\n\t\t\t}\n\t\t\t.q_reviews .reviews_col .review_head{\n\t\t\t\tdisplay: flex;\n\t\t\t\tmargin-bottom: 17px;\n\t\t\t}\n\t\t\t.q_reviews .review_head .avatar{\n\t\t\t\twidth: 46px;\n\t\t\t\tline-height: 0;\n\t\t\t\theight: 46px;\n\t\t\t\toverflow: hidden;\n\t\t\t\tborder-radius: 23px;\n\t\t\t\tmargin-right: 15px;\n\t\t\t\tbackground-size: 102%;\n\t\t\t}\n\t\t\t.q_reviews .review_head .title{\n\t\t\t\talign-self: center;\n\t\t\t\tpadding-top: 5px;\n\t\t\t}\n\t\t\t.q_reviews .review_head .reviewer{\n\t\t\t\tfont-weight: 500;\n\t\t\t\tline-height: 1.2em;\n\t\t\t}\n\t\t\t.q_reviews .review_head .date{\n\t\t\t\tfont-size: 14px;\n\t\t\t}\n\t\t\t.q_reviews .review_head .google_logo{\n\t\t\t\tmargin-left: auto;\n\t\t\t}\n\t\t\t.q_reviews .star_rating .stars{\n\t\t\t\tlist-style: none;\n\t\t\t\tdisplay: flex;\n\t\t\t\tpadding: 0;\n\t\t\t\tmargin-bottom: 8px;\n\t\t\t}\n\t\t\t.q_reviews .star_rating .stars li{\n\t\t\t\tmargin-right: 4px;\n\t\t\t\tpadding-left: 0;\n\t\t\t}\n\t\t\t.q_reviews .star_rating .stars li:before{\n\t\t\t\tdisplay: none;\n\t\t\t}\n\t\t\t.q_reviews .review_content {\n\t\t\t\tmargin-bottom: auto;\n\t\t\t\theight: 126px;\n\t\t\t\ttransition: height 0.5s;\n\t\t\t}\n\t\t\t.q_reviews .review_content p{\n\t\t\t\toverflow: hidden;\n\t\t\t\tdisplay: -webkit-box;\n\t\t\t\t-webkit-line-clamp: 5;\n\t\t\t\t-webkit-box-orient: vertical;\n\t\t\t\tline-height: 25.2px;\n\t\t\t\tfont-weight: 200;\n\t\t\t\tpadding-bottom: 0 !important;\n\t\t\t}\n\t\t\t.q_reviews .reviews_col.overflow .read_more{\n\t\t\t\topacity: 1 !important;\n\t\t\t\tpointer-events: unset !important;\n\t\t\t}\n\t\t\t.q_reviews .reviews_col .read_more{\n\t\t\t\tline-height: 1;\n\t\t\t\tmargin-top: 15px;\n\t\t\t}\n\t\t\t.q_reviews .reviews_col .read_more span{\n\t\t\t\tcolor: #000;\n\t\t\t\tfont-weight: 500;\n\t\t\t\tcursor: pointer;\n\t\t\t}\n\t\t\t.review-button{\n\t\t\t\tdisplay: flex;\n\t\t\t\tjustify-content: center;\n\t\t\t\tmargin-top: 70px;\n\t\t\t}\n\t\t\t.review-button .btn{\n\t\t\t\tdisplay: inline-block;\n\t\t\t\ttext-decoration: none !important;\n    \t\t\tcolor: #fff !important;\n\t\t\t}\n\t\t\t@media (max-width: 980px){\n\t\t\t\tsection.blog-section.customer-review .section-row{\n\t\t\t\t\tflex-direction: column;\n\t\t\t\t}\n\t\t\t\tsection.blog-section.customer-review .google-rating .rating h3 {\n\t\t\t\t\tpadding-bottom: 0px;\n\t\t\t\t\tfont-size: 17px !important;\n\t\t\t\t}\n\t\t\t\t.q_reviews{\n\t\t\t\t\tmargin-top: 5em;\n\t\t\t\t}\n\t\t\t\t.q_reviews .slick-dots{\n\t\t\t\t\tmargin-top: 30px;\n\t\t\t\t}\n\t\t\t\t.review-button{\n\t\t\t\t\tmargin-top: 40px;\n\t\t\t\t}\n\t\t\t}\n\t\t\t@media (max-width: 479px){\n\t\t\t\tsection.blog-section.customer-review {\n\t\t\t\t\tpadding-left: 5%;\n\t\t\t\t\tpadding-right: 5%;\n\t\t\t\t\tpadding-top: 3em;\n\t\t\t\t}\n\t\t\t\t.q_reviews{\n\t\t\t\t\tpadding: 0;\n\t\t\t\t\tmargin-top: 2.5em;\n\t\t\t\t}\n\t\t\t\t.q_reviews .slick-track{\n\t\t\t\t\tgrid-gap: unset;\n\t\t\t\t}\n\t\t\t\t.q_reviews .slick-dots li button{\n\t\t\t\t\twidth: 10px;\n\t\t\t\t\theight: 10px;\n\t\t\t\t\tborder-radius: 5px;\n\t\t\t\t}\n\t\t\t\t.q_reviews .slick-dots{\n\t\t\t\t\tmargin-top: 25px;\n\t\t\t\t}\n\t\t\t\t.review-button{\n\t\t\t\t\tmargin-top: 45px;\n\t\t\t\t}\n\t\t\t}\n\t\t<\/style>\n\t\t<script>\n\t\tjQuery(document).ready(function($) {\n\t\t\t$(\".q_reviews\").slick({\n\t\t\t\t  infinite: true,\n\t\t\t\t  slidesToShow: 3,\n\t\t\t\t  slidesToScroll: 3,\n\t\t\t\t  arrows: true,\n\t\t\t\t  dots: true,\n\t\t\t\t  autoplay: true,\n\t\t\t\t  autoplaySpeed: 2000,\n\t\t\t\t  responsive: [\n\t\t\t\t\t\t\t{\n\t\t\t\t\t\t  breakpoint: 980,\n\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\tslidesToShow: 2,\n\t\t\t\t\t\t\tslidesToScroll: 2,\n\t\t\t\t\t\t  },\n\t\t\t\t\t\t},\n\t\t\t\t\t\t{\n\t\t\t\t\t\t  breakpoint: 479,\n\t\t\t\t\t\t  settings: {\n\t\t\t\t\t\t\tslidesToShow: 1,\n\t\t\t\t\t\t\tslidesToScroll: 1,\n\t\t\t\t\t\t\tarrows: false,\n\t\t\t\t\t\t  },\n\t\t\t\t\t\t},\n\t\t\t\t\t  ],\n\t\t\t\t\t})\n\n\t\t\tjQuery(\".q_reviews .review_content p\").each(function(){\n\t\t\t\th=jQuery(this).height();\n\t\t\t\toh=jQuery(this)[0].scrollHeight;\n\t\t\t\tif(oh > h){\n\t\t\t\t\tjQuery(this).parents(\".reviews_col\").addClass(\"overflow\");\n\t\t\t\t}\n\t\t\t});\n\t\t\tjQuery(\".q_reviews .reviews_col.overflow .read_more span\").click(function(){\n\t\t\t\tif(jQuery(this).hasClass(\"open\")){\n\t\t\t\t\tjQuery(this).removeClass(\"open\");\n\t\t\t\t\tjQuery(this).text(jQuery(this).attr(\"data-collapse\"));\n\t\t\t\t\tjQuery(this).parent().prev().css(\"height\", \"126px\");\n\t\t\t\t\tjQuery(this).parent().prev().children(\"p\").css(\"-webkit-line-clamp\", \"5\");\n\t\t\t\t}\n\t\t\t\telse{\n\t\t\t\t\tjQuery(this).addClass(\"open\");\n\t\t\t\t\tjQuery(this).text(jQuery(this).attr(\"data-open\"));\n\t\t\t\t\tvar h= jQuery(this).parent().prev().children(\"p\")[0].scrollHeight;\n\t\t\t\t\tjQuery(this).parent().prev().css(\"height\", h+\"px\");\n\t\t\t\t\tjQuery(this).parent().prev().children(\"p\").css(\"-webkit-line-clamp\", \"unset\");\n\t\t\t\t}\n\t\t\t});\n\t\t});\n\t\t<\/script>\n\t\t<script type=\"application\/ld+json\">\n\n\t\t{ \"@context\":\"http:\/\/schema.org\",\n\n\t\t\"@type\":\"Organization\",\n\n\t\t\"address\":{\n\n\t\t\"@type\":\"PostalAddress\",\n\n\t\t\"addressCountry\":\"Switzerland\",\n\n\t\t\"addressLocality\":\"Frauenfeld\",\n\n\t\t\"postalCode\":\"8500\",\n\n\t\t\"streetAddress\":\"Gerlikonerstrasse 7\"\n\n\t\t},\n\n\t\t\"aggregateRating\":{\n\n\t\t\"@type\":\"AggregateRating\",\n\n\t\t\"bestRating\":\"5\",\n\n\t\t\"ratingCount\":\"31\",\n\n\t\t\"ratingValue\":\"5.0\",\n\n\t\t\"worstRating\":\"5\"\n\n\t\t},\n\n\t\t\"email\":\"info@nexova.ch\",\n\n\t\t\"logo\":{\n\n\t\t\"@type\":\"ImageObject\",\n\n\t\t\"name\":\"NEXOVA\",\n\n\t\t\"url\":\"https:\/\/www.nexova.ch\/wp-content\/uploads\/2022\/05\/logo.svg\"\n\n\t\t},\n\n\t\t\"name\":\"NEXOVA\",\n\n\t\t\"telephone\": \"+41445624560\",\n\n\t\t\"url\": \"https:\/\/www.nexova.ch\/de\/\"\n\n\t\t}\n\n\t\t<\/script>\n\t<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Finanzoperationen sind der Motor, der die Entwicklung eines Unternehmens antreibt. Doch in der heutigen Gesch\u00e4ftswelt ist die Transformation greifbar: Finanzielle Klarheit, Genauigkeit in Transaktionen und optimierte Arbeitsabl\u00e4ufe sind nicht nur erreichbar, sondern auch zug\u00e4nglicher denn je dank moderner Business- und Buchhaltungssoftware.<\/p>\n<p>Inmitten dieser Vielfalt an L\u00f6sungen steht die Kreditorensoftware im Rampenlicht. Auf unserer gemeinsamen Reise in diesem Blog werden wir ein Profil eines herausragenden Anw\u00e4rters auf dem heutigen Markt erstellen &#8211; besonders f\u00fcr Schweizer Unternehmer und KMU. Bereit, die Zukunft des Finanzmanagements zu erkunden?<\/p>\n","protected":false},"author":5,"featured_media":15272,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","q_post_updated_date":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-15296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buchhaltung"],"_links":{"self":[{"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/posts\/15296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/comments?post=15296"}],"version-history":[{"count":5,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/posts\/15296\/revisions"}],"predecessor-version":[{"id":30891,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/posts\/15296\/revisions\/30891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/media\/15272"}],"wp:attachment":[{"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/media?parent=15296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/categories?post=15296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nexova.ch\/de\/wp-json\/wp\/v2\/tags?post=15296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}